{"id":14986,"date":"2024-11-04T04:22:53","date_gmt":"2024-11-03T22:52:53","guid":{"rendered":"https:\/\/politicsrights.com\/?p=14986"},"modified":"2025-09-15T02:16:59","modified_gmt":"2025-09-14T19:46:59","slug":"how-emotions-shape-climate-action","status":"publish","type":"post","link":"https:\/\/politicsrights.com\/es\/how-emotions-shape-climate-action\/","title":{"rendered":"C\u00f3mo las emociones moldean la acci\u00f3n clim\u00e1tica: Barreras y agencia"},"content":{"rendered":"<h2 class=\"wp-block-heading\">La urgencia de la adaptaci\u00f3n clim\u00e1tica<\/h2>\n\n\n\n<p class=\"translation-block\">Si hemos aprendido algo de las \u00faltimas cuatro d\u00e9cadas de falta de avances frente a la emergencia clim\u00e1tica, es esto: <strong>no habr\u00e1 soluciones m\u00e1gicas ni l\u00edderes supremos capaces de sacarnos del l\u00edo que hemos creado<\/strong> y evitar lo que bien podr\u00eda ser un colapso de las civilizaciones a medida que nuestro planeta sigue calent\u00e1ndose.<\/p>\n\n\n\n<p class=\"translation-block\">Ahora enfrentamos la inevitabilidad de numerosos impactos importantes y la necesidad de una transici\u00f3n en nuestros sistemas sociales a una velocidad y escala sin precedentes si queremos evitar ese posible colapso. <strong>Sin precedentes, ciertamente, pero no imposible.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Un factor estrechamente vinculado a la preocupaci\u00f3n clim\u00e1tica es el cuidado de los dem\u00e1s, en particular de aquellos fuera de nuestro grupo cercano.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"translation-block\">Para lograrlo, debemos activar ese mismo motor que ha precipitado cambios sociales a lo largo de la historia: <strong>las personas, comprometi\u00e9ndose y organiz\u00e1ndose para apoyar ese cambio.<\/strong> La \u00fanica manera en que ocurre un cambio social intencional es cuando los actores reflexivos deciden problematizar nuestras circunstancias actuales y se comprometen a enfrentarlas, de forma individual, pero a\u00fan m\u00e1s importante, de manera colectiva. Nuestra respuesta a la emergencia clim\u00e1tica no ser\u00e1 diferente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Barreras, emociones y respuestas clim\u00e1ticas<\/h2>\n\n\n\n<p class=\"translation-block\"><strong>Si fuera as\u00ed de sencillo, \u00bfpor qu\u00e9 no lo hemos hecho ya?<\/strong> Entre las muchas razones se\u00f1aladas por los cient\u00edficos sociales en temas de clima est\u00e1n los factores estructurales como el poder y la pol\u00edtica, el consumismo y la desinformaci\u00f3n. Tambi\u00e9n influyen en gran medida los intereses personales en mantener la riqueza, los estilos de vida y las creencias culturales que est\u00e1n \u00edntimamente ligados a actividades intensivas en emisiones de gases de efecto invernadero.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote alignleft\"><blockquote><p>Algunas emociones se sienten bien: orgullo, alegr\u00eda, amor, entusiasmo; y otras se sienten mal: verg\u00fcenza, miedo, culpa y desesperaci\u00f3n.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"translation-block\">Sin embargo, las fuerzas estructurales y las amenazas y oportunidades materiales personales no son, de ninguna manera, los \u00fanicos motores de las respuestas sociales a la emergencia clim\u00e1tica. <strong>Las respuestas personales y sociales a la emergencia clim\u00e1tica tambi\u00e9n tienen que ver con la emocionalidad<\/strong>, tanto como medio para que operen el poder, la pol\u00edtica, la desinformaci\u00f3n, el consumismo y el inter\u00e9s personal, como una dimensi\u00f3n aut\u00f3noma de la capacidad de actuar.<\/p>\n\n\n\n<p class=\"translation-block\">De hecho, una importante base de investigaci\u00f3n indica que <strong>un factor estrechamente vinculado a la preocupaci\u00f3n clim\u00e1tica es el cuidado de los dem\u00e1s,<\/strong> en particular de aquellos fuera de nuestro grupo cercano. Esto incluye el cuidado y una sensaci\u00f3n de conexi\u00f3n con los otros no humanos y con la Naturaleza. Tambi\u00e9n intervienen muchas otras emociones.<\/p>\n\n\n\n<p class=\"translation-block\">Estas respuestas emocionales al cambio clim\u00e1tico son el tema central de mi nuevo libro, <em><a href=\"https:\/\/www.routledge.com\/Feeling-Climate-Change-How-Emotions-Govern-Our-Responses-to-the-Climate-Emergency\/Davidson\/p\/book\/9781032462769?srsltid=AfmBOop1gJtEzMTKZ9D7eXtftiJmSPMiMQ_Md8Imaf24YNVFjBfV04Di\" target=\"_blank\" rel=\"noopener\">Sentir el cambio clim\u00e1tico: C\u00f3mo las emociones gobiernan nuestras respuestas a la emergencia clim\u00e1tica<\/a><\/em> (2024, Routledge), que explora las preguntas: \u00bfC\u00f3mo importan las emociones en las respuestas sociales a la emergencia clim\u00e1tica? \u00bfQu\u00e9 diferencia los caminos emocionales hacia la acci\u00f3n de aquellos que favorecen la inacci\u00f3n? \u00bfY c\u00f3mo puede este conocimiento informar la defensa del clima de manera productiva?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Algunas cosas que decir sobre las emociones<\/h2>\n\n\n\n<p class=\"translation-block\">Contrario a las primeras interpretaciones de las ciencias sociales que retrataban las emociones como el hermano molesto de la raz\u00f3n, la investigaci\u00f3n en neurociencias en las \u00faltimas d\u00e9cadas ha dejado claro que <strong>las emociones juegan roles cruciales en nuestro comportamiento y toma de decisiones.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"525\" src=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions.webp\" alt=\"Cover: Feeling Climate ChangeHow Emotions Govern Our Responses to the Climate Emergency\" class=\"wp-image-14999 size-full\" srcset=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions.webp 350w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-200x300.webp 200w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-8x12.webp 8w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<figure class=\"wp-block-pullquote\"><blockquote><p>Sentir el cambio clim\u00e1tico revela c\u00f3mo nuestras emociones impulsan la acci\u00f3n colectiva necesaria para abordar la crisis clim\u00e1tica.<\/p><\/blockquote><\/figure>\n<\/div><\/div>\n\n\n\n<p class=\"translation-block\"><strong>Las emociones son nuestro medio para responder a la informaci\u00f3n y los est\u00edmulos de nuestro entorno<\/strong>, atrayendo nuestra atenci\u00f3n hacia temas de preocupaci\u00f3n: a nuestra propia supervivencia y bienestar, y tambi\u00e9n a las cosas que valoramos, como los dem\u00e1s dentro y fuera de nuestras redes sociales, nuestras comunidades, los animales, los paisajes, o la democracia y la justicia.<\/p>\n\n\n\n<p class=\"translation-block\">Esta comprensi\u00f3n de las emociones es particularmente relevante para nuestras respuestas personales a la informaci\u00f3n sobre el cambio clim\u00e1tico: <strong>esos detonantes emocionales, que son el punto de partida para la toma de decisiones y la acci\u00f3n, deben sentirse, no solo escucharse.<\/strong> En otras palabras, la informaci\u00f3n por s\u00ed sola no es suficiente; esa informaci\u00f3n debe estar vinculada por el receptor a algo que valore.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Necesidades humanas b\u00e1sicas y respuestas emocionales<\/h2>\n\n\n\n<p>Nuestro bagaje emocional, rico pero a veces desordenado, se desarroll\u00f3 para apoyar la supervivencia, a trav\u00e9s de la vida en grupo y la cooperaci\u00f3n que esta facilita.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"560\" src=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-UN-Development-Programme-in-Europe-and-CIS.webp\" alt=\"Two children hold a distressed-looking Earth above rising waters, their faces reflecting worry and sadness. Smoke billows from an industrial plant in the background, adding to the sense of urgency and emotional weight of the scene. This illustration captures the concern and emotional impact of climate change on younger generations\" class=\"wp-image-15021\" srcset=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-UN-Development-Programme-in-Europe-and-CIS.webp 799w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-UN-Development-Programme-in-Europe-and-CIS-300x210.webp 300w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-UN-Development-Programme-in-Europe-and-CIS-768x538.webp 768w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/emotions-UN-Development-Programme-in-Europe-and-CIS-18x12.webp 18w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><figcaption class=\"wp-element-caption\">Con expresiones de preocupaci\u00f3n, dos ni\u00f1os sostienen una Tierra fr\u00e1gil mientras las aguas suben y el humo industrial se cierne en el fondo, capturando el impacto emocional del cambio clim\u00e1tico en las generaciones futuras. Imagen del Programa de las Naciones Unidas para el Desarrollo en Europa y la CEI.<\/figcaption><\/figure>\n\n\n\n<p class=\"translation-block\"><strong>Esa emocionalidad est\u00e1 en muchos aspectos vinculada a la satisfacci\u00f3n de algunas necesidades humanas b\u00e1sicas adem\u00e1s de la supervivencia f\u00edsica,<\/strong> incluyendo dos en particular que a veces est\u00e1n en tensi\u00f3n: <em>la autonom\u00eda<\/em>, facilitada por un sentido de eficacia y la capacidad de reflexionar; y <em>el sentido de pertenencia<\/em>, que nos proporciona seguridad ontol\u00f3gica e identidad.<\/p>\n\n\n\n<p class=\"translation-block\"><strong>Las emociones m\u00e1s pertinentes a estas necesidades humanas son la culpa, la verg\u00fcenza, el orgullo y la empat\u00eda,<\/strong> las cuales discuto en detalle en el libro. Un segundo punto importante sobre las emociones que nos ense\u00f1a la neurociencia, y que es particularmente relevante para nuestras respuestas a la emergencia clim\u00e1tica: algunas emociones se sienten bien: orgullo, alegr\u00eda, amor, entusiasmo; y otras se sienten mal: verg\u00fcenza, miedo, culpa y desesperaci\u00f3n.<\/p>\n\n\n\n<p class=\"translation-block\">Tendemos a gravitar hacia situaciones, personas e informaci\u00f3n que est\u00e1n asociadas con esas emociones positivas, y alejarnos de aquellas que generan emociones negativas. Avanzar intencionalmente hacia las emociones negativas y sentarse con ellas, como a veces debemos hacer, <strong>requiere una tremenda cantidad de esfuerzo y compromiso.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estructuras sociales que moldean las emociones<\/h2>\n\n\n\n<p class=\"translation-block\">Hay otra caracter\u00edstica importante de nuestra emocionalidad que tiende a no discutirse mucho entre los neurocient\u00edficos, pero que ha sido resaltada por soci\u00f3logos, ge\u00f3grafos y otros: las estructuras sociales son parte de ese entorno al cual respondemos emocionalmente, <strong>y esas estructuras tambi\u00e9n moldean nuestra emocionalidad,<\/strong> al ofrecer recompensas a ciertas personas y ciertos comportamientos, y sanciones a otros.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote alignright\"><blockquote><p>El n\u00famero de personas en todo el mundo que est\u00e1n personalmente comprometidas en actuar sigue creciendo.<\/p><\/blockquote><\/figure>\n\n\n\n<p>En el libro analizo tres estructuras -capitalismo, colonialismo y patriarcado- que impregnan las instituciones sociales modernas, dividi\u00e9ndonos en compartimentos de los empoderados y los despose\u00eddos, los agentes y los objetos. <\/p>\n\n\n\n<p class=\"translation-block\"><strong>Estas estructuras tienen efectos particularmente perjudiciales en nuestra capacidad para enfrentar la emergencia clim\u00e1tica,<\/strong> no solo directamente, al favorecer una explotaci\u00f3n desmedida del mundo natural, sino tambi\u00e9n indirectamente, al sofocar aquellas capacidades humanas que de otro modo se activar\u00edan para abordar los problemas de acci\u00f3n colectiva resultantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Capitalismo y respuestas emocionales<\/h2>\n\n\n\n<p class=\"translation-block\">Tomemos el capitalismo, por ejemplo. <strong>El impacto directo del capitalismo sobre el mundo natural es evidente,<\/strong> impulsado por los incentivos estructurales para la explotaci\u00f3n y generaci\u00f3n de valor excedente, y la creaci\u00f3n de demanda material a trav\u00e9s del consumismo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND.webp\" alt=\"Una joven manifestante sonr\u00ede con determinaci\u00f3n, sosteniendo un cartel que dice &quot;Compostar el capitalismo&quot;, mientras el aire se llena de emociones de esperanza, frustraci\u00f3n y resiliencia. El grupo a su alrededor, con los rostros pintados de verde, canaliza su pasi\u00f3n colectiva en un llamado por un cambio ambiental y sist\u00e9mico, encarnando tanto la alegr\u00eda de la comunidad como la urgencia de su mensaje.\" class=\"wp-image-15018\" srcset=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND.webp 799w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND-300x200.webp 300w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND-768x512.webp 768w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND-18x12.webp 18w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND-330x220.webp 330w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND-420x280.webp 420w, https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Emotions-facing-climate-change-Stephen-Melkisethian-CC-BY-NC-ND-615x410.webp 615w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><figcaption class=\"wp-element-caption\">Holding a sign that reads &#8216;Compost Capitalism,&#8217; a young protester joins others in calling for a transformation of the capitalist system, seen as environmentally unsustainable. Photo by Stephen Melkisethian (CC BY-NC-ND).<\/figcaption><\/figure>\n\n\n\n<p class=\"translation-block\"><strong>Sin embargo, el capitalismo tambi\u00e9n deja su huella en nuestra emocionalidad.<\/strong> Entre otras cosas, el capitalismo regula nuestra emocionalidad para fomentar la aquiescencia y nos define como trabajadores y consumidores atomizados.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote alignleft\"><blockquote><p>La esperanza tiene que ver mucho m\u00e1s con las potencialidades que con las probabilidades.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"translation-block\">La <strong>individualidad, la agresi\u00f3n, las inseguridades personales<\/strong> y, sobre todo, el miedo, son los tipos de emociones que se permiten florecer en un sistema capitalista, mientras que las emociones que fomentan la construcci\u00f3n de comunidad, que es en \u00faltima instancia la fuente m\u00e1s fuerte de resistencia al capitalismo, no son recompensadas, sino sancionadas.<\/p>\n\n\n\n<p class=\"translation-block\"><strong>El capitalismo es, en efecto, un asesino de comunidades, cultivando la individualidad, el ego\u00edsmo, la desmotivaci\u00f3n y los miedos asociados,<\/strong> mientras que compromete nuestras capacidades inherentes de cooperaci\u00f3n y vida en colectivo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Caminos hacia la inacci\u00f3n clim\u00e1tica<\/h2>\n\n\n\n<p class=\"translation-block\">As\u00ed, todos hemos heredado una emocionalidad rica y compleja, <strong>incluyendo aquellas emociones que apoyan directamente nuestra alta capacidad de cooperaci\u00f3n.<\/strong> Sin embargo, tambi\u00e9n estamos inmersos en sistemas sociales que nos dividen. Adem\u00e1s, como se mencion\u00f3 anteriormente, los detonantes de acci\u00f3n deben sentirse, no solo escucharse, y, sin embargo, la informaci\u00f3n sobre el cambio clim\u00e1tico a menudo se presenta de manera que su relevancia para las cosas que valoramos queda oscurecida por un lenguaje cient\u00edfico y tecnocr\u00e1tico. Estas son algunas de las razones clave por las que la inacci\u00f3n clim\u00e1tica es tan prevalente en las sociedades occidentales.<\/p>\n\n\n\n<p class=\"rb-list translation-block\">La inacci\u00f3n clim\u00e1tica puede entenderse adem\u00e1s como el seguimiento de cuatro caminos emocionales distintos, descritos en detalle en <em>Sentir el cambio clim\u00e1tico<\/em>.<\/p>\n\n\n\n<ul class=\"wp-block-list rb-list\">\n<li class=\"translation-block\"><strong>La apat\u00eda,<\/strong> por ejemplo, describe la falta de atenci\u00f3n: ese detonante emocional simplemente no se activa, tal vez como resultado de vidas ocupadas y estresantes que absorben nuestra atenci\u00f3n emocional, o el sesgo de optimismo: la creencia de que todo estar\u00e1 bien.<\/li>\n\n\n\n<li class=\"translation-block\"><strong>La negaci\u00f3n,<\/strong> en cambio, describe una respuesta fuertemente emocional a la informaci\u00f3n clim\u00e1tica, pero para estas personas, no es el cambio clim\u00e1tico en s\u00ed, sino las implicaciones de la ciencia y las pol\u00edticas clim\u00e1ticas, percibidas como una amenaza tal que llevan al rechazo.<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Las respuestas de muchos otros hoy podr\u00edan describirse como retiro:<\/strong> un alto grado de alarma, que se traduce en ansiedad por la emergencia clim\u00e1tica, combinado con una baja eficacia personal, lo cual motiva a estas personas a apartarse.<\/li>\n\n\n\n<li class=\"translation-block\"><strong>Y luego est\u00e1 una cuarta categor\u00eda, aquellos que est\u00e1n de acuerdo en que el cambio clim\u00e1tico es una preocupaci\u00f3n seria y tienen la capacidad personal para hacer algo al respecto, pero no lo hacen.<\/strong> En cambio, estas personas se sienten atrapadas en un estado de disonancia cognitiva que puede llevar a sentimientos de desesperanza, posiblemente en parte debido a una baja eficacia colectiva percibida \u2013 en otras palabras, el cinismo \u2013 sobre si su participaci\u00f3n en acciones personales y colectivas har\u00e1 alguna diferencia.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Mecanismos de agencia para la acci\u00f3n clim\u00e1tica<\/h2>\n\n\n\n<p class=\"translation-block\">A pesar de las muchas caracter\u00edsticas de nuestras vidas que favorecen la inacci\u00f3n, el n\u00famero de personas en todo el mundo que est\u00e1n personalmente comprometidas en actuar sigue creciendo. Para estas personas, <strong>el detonante emocional ha dado en el blanco, en alguien con alta eficacia personal y colectiva.<\/strong><\/p>\n\n\n\t\t<div class=\"related-sec related-6 is-width-wide is-style-boxed\">\r\n\t\t\t<div class=\"inner block-grid-small-1 rb-columns rb-col-3 is-gap-10\">\r\n\t\t\t\t<div class=\"block-h heading-layout-2\"><div class=\"heading-inner\"><h3 class=\"heading-title none-toc\"><span>Leer m\u00e1s<\/span><\/h3><\/div><\/div>\t\t\t\t<div class=\"block-inner\">\r\n\t\t\t\t\t\t\t<div class=\"p-wrap p-grid p-grid-small-1\" data-pid=\"14585\">\r\n\t\t\t\t\t<div class=\"feat-holder\">\r\n\t\t\t\t\t\t<div class=\"p-featured\">\r\n\t\t\t\t\t<a class=\"p-flink\" href=\"https:\/\/politicsrights.com\/es\/does-humanity-have-a-death-wish\/\" title=\"\u00bfTiene la humanidad un deseo de muerte?\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"220\" src=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Humanity-Kim-Seng-ND-330x220.webp\" class=\"featured-img wp-post-image\" alt=\"Chimeneas industriales liberando humo en el cielo, destacando el impacto ambiental de la actividad humana en el planeta y los desaf\u00edos que enfrenta la humanidad con la contaminaci\u00f3n y el cambio clim\u00e1tico.\" \/>\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"p-content\">\r\n\t\t\t<div class=\"entry-title h5\">\t\t<a class=\"p-url\" href=\"https:\/\/politicsrights.com\/es\/does-humanity-have-a-death-wish\/\" rel=\"bookmark\">\r\n\t\t\u00bfTiene la humanidad un deseo de muerte?\t\t<\/a>\r\n\t\t<\/div>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"p-wrap p-grid p-grid-small-1\" data-pid=\"12378\">\r\n\t\t\t\t\t<div class=\"feat-holder\">\r\n\t\t\t\t\t\t<div class=\"p-featured\">\r\n\t\t\t\t\t<a class=\"p-flink\" href=\"https:\/\/politicsrights.com\/es\/ethics-for-the-end-times\/\" title=\"\u00c9tica para el fin de los tiempos\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"220\" src=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/07\/Red-Rebel-Ethics-Bhuwan-Bansal--330x220.webp\" class=\"featured-img wp-post-image\" alt=\"Miembros de los Red Rebels, parte del movimiento Extinction Rebellion, realizan una protesta silenciosa contra el cambio clim\u00e1tico. Foto por Bhuwan Bansal\" \/>\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"p-content\">\r\n\t\t\t<div class=\"entry-title h5\">\t\t<a class=\"p-url\" href=\"https:\/\/politicsrights.com\/es\/ethics-for-the-end-times\/\" rel=\"bookmark\">\r\n\t\t\u00c9tica para el fin de los tiempos\t\t<\/a>\r\n\t\t<\/div>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"p-wrap p-grid p-grid-small-1\" data-pid=\"12186\">\r\n\t\t\t\t\t<div class=\"feat-holder\">\r\n\t\t\t\t\t\t<div class=\"p-featured\">\r\n\t\t\t\t\t<a class=\"p-flink\" href=\"https:\/\/politicsrights.com\/es\/vulnerability-climate-change-human-rights\/\" title=\"Encuadre de la vulnerabilidad en derechos humanos y cambio clim\u00e1tico por la ONU\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"220\" src=\"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/07\/Vunerability-Photo-by-Juan-Carlos-Huayllapuma-CIFOR-_CC-BY-NC-ND-_1_-compressed-330x220.webp\" class=\"featured-img wp-post-image\" alt=\"Una mujer con atuendo tradicional est\u00e1 sentada bajo un \u00e1rbol, cosiendo meticulosamente una tela con patrones. A su lado, dos ni\u00f1os descansan sobre una plataforma de madera, rodeados de mantas vibrantes y una vegetaci\u00f3n frondosa, capturando un momento de la vida cotidiana y vulnerabilidad en un entorno rural.\" \/>\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"p-content\">\r\n\t\t\t<div class=\"entry-title h5\">\t\t<a class=\"p-url\" href=\"https:\/\/politicsrights.com\/es\/vulnerability-climate-change-human-rights\/\" rel=\"bookmark\">\r\n\t\tEncuadre de la vulnerabilidad en derechos humanos y cambio clim\u00e1tico por la ONU\t\t<\/a>\r\n\t\t<\/div>\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n\n<p class=\"translation-block\">Pero la acci\u00f3n sostenida tambi\u00e9n debe tener recompensas emocionales positivas, y <strong>la capacidad de actuar no surge autom\u00e1ticamente,<\/strong> incluso en presencia de condiciones tan favorables como la preocupaci\u00f3n y la eficacia. Como se detalla en el libro, la presencia de uno o m\u00e1s <em>mecanismos de agencia<\/em> es crucial.<\/p>\n\n\n\n<p class=\"translation-block\"><em>Sentir el cambio clim\u00e1tico<\/em> describe <strong>siete mecanismos,<\/strong> incluyendo: normas de responsabilidad, eficacia, pertenencia, empat\u00eda, pensamiento de complejidad, visi\u00f3n a futuro y esperanza, de <strong>los cuales tres se desarrollan brevemente a continuaci\u00f3n.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La pertenencia como catalizador del cambio<\/h2>\n\n\n\n<p><em>Belonging<\/em> is a basic human need, the absence of which is nothing short of emotionally debilitating. Anyone, even members of privileged positionalities, who contemplate beliefs and actions that conflict with the dominant norms and beliefs of their in-group, can feel alienated.<\/p>\n\n\n\n<p class=\"translation-block\">Como resultado, la primera tentaci\u00f3n de aquellos individuos que se encuentran cuestionando las creencias, normas y pr\u00e1cticas de sus grupos es guardar silencio, <strong>para evitar la verg\u00fcenza que podr\u00eda resultar de una confrontaci\u00f3n grupal.<\/strong> Pero esos individuos tambi\u00e9n pueden, y de hecho lo hacen, empezar a mirar m\u00e1s all\u00e1 de las fronteras del grupo, para ver si podr\u00eda haber otro grupo m\u00e1s alineado con su identidad personal en evoluci\u00f3n.<\/p>\n\n\n\n<p class=\"translation-block\">Buscar pertenencia en nuevos grupos y redes sociales puede entonces <strong>llevar a la exposici\u00f3n a nueva informaci\u00f3n, normas y valores que validan en lugar de avergonzar.<\/strong> La reorientaci\u00f3n de las redes sociales de una persona crea as\u00ed espacios para imaginar nuevas creencias y pr\u00e1cticas, y esas redes, a su vez, brindan el apoyo emocional para adoptar esas creencias y practicar esos valores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El papel de la empat\u00eda en la defensa del clima<\/h2>\n\n\n\n<p class=\"translation-block\">Posiblemente la emoci\u00f3n m\u00e1s importante con influencia en las respuestas sociales a la emergencia clim\u00e1tica, <em>la empat\u00eda<\/em> es bastante compleja, <strong>y consta de tres elementos<\/strong> seg\u00fan Jean Decety y sus colegas: <em>compartir afectivo<\/em>, que describe una respuesta autom\u00e1tica a una situaci\u00f3n que otro ser est\u00e1 experimentando; <em>preocupaci\u00f3n emp\u00e1tica<\/em>, que describe el grado en que el observador siente inter\u00e9s y cuidado por lo que el otro ser est\u00e1 experimentando; y <em>tomar perspectiva<\/em>, una capacidad cognitiva de ponerse en el lugar de otro, que, en el caso de Otros diferentes, implica una elecci\u00f3n deliberada de invertir el esfuerzo mental necesario para hacerlo.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote alignright\"><blockquote><p>Si no actuamos en base a la esperanza cuando esta surge, se desvanecer\u00e1 r\u00e1pidamente.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"translation-block\"><strong>La empat\u00eda se invoca m\u00e1s f\u00e1cilmente en respuesta a situaciones enfrentadas por otros de nuestros grupos de pertenencia<\/strong> \u2014familia, comunidad, compa\u00f1eros de equipo, compa\u00f1eros de trabajo, as\u00ed como identidades \u00e9tnicas, pol\u00edticas o nacionales.<\/p>\n\n\n\n<p class=\"translation-block\">Estas expresiones de empat\u00eda de grupo pueden, en ciertas circunstancias, apoyar la acci\u00f3n pro-clim\u00e1tica, en particular en situaciones en las que los miembros de ese grupo <a href=\"https:\/\/politicsrights.com\/es\/encuadre-vulnerabilidad-derechos-humanos-cambio-climatico-onu\/\" data-type=\"post\" data-id=\"12186\" target=\"_self\">son particularmente vulnerables a los impactos del cambio clim\u00e1tico.<\/a><\/p>\n\n\n\n<p class=\"translation-block\">La empat\u00eda de grupo tiene un doble efecto, sin embargo, influyendo, por ejemplo, en si uno experimenta miedo <em>por<\/em> los refugiados clim\u00e1ticos, o miedo <em>de<\/em> los refugiados clim\u00e1ticos. Por esta raz\u00f3n, <strong>expandir nuestros mapas de empat\u00eda,<\/strong> utilizando la expresi\u00f3n de Arlie Hochschild, es un elemento importante para la acci\u00f3n pro-clim\u00e1tica. La expansi\u00f3n de los mapas de empat\u00eda es algo que todos podemos hacer, y muchos de nosotros ya lo hemos hecho de diversas maneras.<\/p>\n\n\n\n<p class=\"translation-block\"><strong>Ciertas experiencias personales pueden llevar a la expansi\u00f3n del mapa de empat\u00eda,<\/strong> por ejemplo, cuando esas experiencias son compartidas entre personas que no est\u00e1n actualmente en nuestros grupos de pertenencia. Tambi\u00e9n tenemos la capacidad de sentir empat\u00eda hacia otros no humanos, cuya cultivaci\u00f3n tambi\u00e9n facilita la acci\u00f3n pro-clim\u00e1tica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La esperanza como motivadora del compromiso<\/h2>\n\n\n\n<p class=\"translation-block\">El tercer y \u00faltimo mecanismo de agencia en el que me centrar\u00e9 aqu\u00ed es <em>la esperanza<\/em>. La esperanza requiere contemplaci\u00f3n; en otras palabras, es un sentimiento que demanda la participaci\u00f3n plena de nuestros l\u00f3bulos frontales. <strong>Aceptar la esperanza tambi\u00e9n refleja un compromiso con la incertidumbre.<\/strong> La esperanza tiene que ver mucho m\u00e1s con las potencialidades que con las probabilidades. La esperanza se siente en el presente, pero la visi\u00f3n o el objetivo que inspira la esperanza a\u00fan no ha llegado, y podr\u00eda no llegar nunca.<\/p>\n\n\n\n<p class=\"translation-block\">De hecho, el propio concepto de esperanza implica una conciencia de la posibilidad de que el objeto de esperanza nunca llegue a suceder. <strong>Un gran error que comete mucha gente es confundir la esperanza con el optimismo.<\/strong> Si soy optimista respecto a que un resultado espec\u00edfico suceda, significa que creo que la probabilidad de que ese resultado ocurra es mayor que la de que no ocurra. La esperanza es algo completamente distinto. Yo <em>espero<\/em> cuando las probabilidades son peque\u00f1as, quiz\u00e1 incluso m\u00ednimas. \u00bfPor qu\u00e9 podr\u00eda estar inclinado a asumir una postura aparentemente tan irracional?<\/p>\n\n\n\n<p class=\"translation-block\">Ciertamente, no asignamos esperanza a cada situaci\u00f3n con bajas probabilidades de \u00e9xito. Esperamos, a pesar de las pocas probabilidades de \u00e9xito, cuando el resultado en cuesti\u00f3n es algo que nos importa profundamente. <strong>La esperanza media nuestros miedos y nos permite actuar a pesar de ellos.<\/strong> La esperanza motiva el compromiso y lo sostiene, especialmente cuando se convierte en una experiencia emocional colectiva. La esperanza tambi\u00e9n inspira creatividad en la acci\u00f3n colectiva.<\/p>\n\n\n\n<p class=\"translation-block\">Esa creatividad es particularmente importante frente a la emergencia clim\u00e1tica, en la que el objeto de esperanza es dif\u00edcil de definir. En esta situaci\u00f3n, se hace fundamental la activaci\u00f3n de imaginarios de futuros. Sin una visi\u00f3n, incluso ut\u00f3pica, de futuros posibles, \u00bfen qu\u00e9 podr\u00eda apoyarse la esperanza? La esperanza, sin embargo, es dif\u00edcil de mantener. <strong>Si no actuamos en base a la esperanza cuando esta surge, se desvanecer\u00e1 r\u00e1pidamente.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo nos ayuda este conocimiento?<\/h2>\n\n\n\n<p class=\"translation-block\">Todos enfrentamos la necesidad de ahondar m\u00e1s que nunca para apoyar el compromiso y la cooperaci\u00f3n necesarios para respaldar la adaptaci\u00f3n y mitigaci\u00f3n clim\u00e1ticas, <strong>al mismo tiempo que nuestra capacidad emocional para hacerlo est\u00e1 al l\u00edmite.<\/strong><\/p>\n\n\n\n<p class=\"translation-block\">Adem\u00e1s de esto, <strong>nuestra inteligencia emocional ha sido seriamente comprometida por el capitalismo, el colonialismo y el patriarcado.<\/strong> Superar las barreras <em>emocionales<\/em> para la acci\u00f3n clim\u00e1tica es, por tanto, primordial.<\/p>\n\n\n\n<p class=\"translation-block\">Esto sugiere la necesidad de redirigir los esfuerzos de defensa del clima hacia evaluaciones no solo de las huellas de carbono personales, sino de c\u00f3mo contribuyen a la construcci\u00f3n de capacidad emocional para inversiones cooperativas en la transici\u00f3n social, mediante el cultivo y el enriquecimiento de esas necesidades humanas b\u00e1sicas con las que comenzamos: autonom\u00eda, incluyendo tanto la eficacia como la reflexividad, y pertenencia. Lo m\u00e1s importante, <strong>la acci\u00f3n clim\u00e1tica debe ser un trabajo de amor, no solo de miedo.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>If we have learned anything from the past four decades of non-progress in the face of the climate emergency, it is this: there will be no silver bullets or supreme leaders capable of getting us through the mess we have created&#8230;<\/p>","protected":false},"author":86,"featured_media":15015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":279,"footnotes":""},"categories":[5,1048],"tags":[135,734,1056],"ppma_author":[1084],"class_list":{"0":"post-14986","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-books","8":"category-environment-animals","9":"tag-climate-change","10":"tag-environment","11":"tag-psychology"},"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","authors":[{"term_id":1084,"user_id":86,"is_guest":0,"slug":"debra-davidson","display_name":"Debra Davidson","avatar_url":{"url":"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Debra-Davidson.webp","url2x":"https:\/\/politicsrights.com\/wp-content\/uploads\/2024\/10\/Debra-Davidson.webp"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/posts\/14986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/comments?post=14986"}],"version-history":[{"count":1,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/posts\/14986\/revisions"}],"predecessor-version":[{"id":24469,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/posts\/14986\/revisions\/24469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/media\/15015"}],"wp:attachment":[{"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/media?parent=14986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/categories?post=14986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/tags?post=14986"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/politicsrights.com\/es\/wp-json\/wp\/v2\/ppma_author?post=14986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}